{"id":38,"count":1,"description":"","link":"https:\/\/mde.biologia.gr\/dimpa\/tag\/%ce%b8%ce%ad%ce%bc%ce%b1%cf%84%ce%b1\/","name":"\u03b8\u03ad\u03bc\u03b1\u03c4\u03b1","slug":"%ce%b8%ce%ad%ce%bc%ce%b1%cf%84%ce%b1","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mde.biologia.gr\/dimpa\/wp-json\/wp\/v2\/tags\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mde.biologia.gr\/dimpa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mde.biologia.gr\/dimpa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mde.biologia.gr\/dimpa\/wp-json\/wp\/v2\/posts?tags=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}